
{"id":688,"date":"2018-05-16T10:05:16","date_gmt":"2018-05-16T10:05:16","guid":{"rendered":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/?p=688"},"modified":"2018-05-16T10:05:16","modified_gmt":"2018-05-16T10:05:16","slug":"diario-de-nuestra-clase","status":"publish","type":"post","link":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2018\/05\/16\/diario-de-nuestra-clase\/","title":{"rendered":"DIARIO DE NUESTRA CLASE"},"content":{"rendered":"<p>Viernes, 11 de mayo de 2018<\/p>\n<p>Hola Diario: Hoy cuando llegamos a la fila nos pusimos a jugar y cuando llego Hector subimos a clase. A primera hora tuvimos ingles pero Yolanda no estaba, Inma nos dio los examenes de ingles para hacerlos, tuvimos tiempo desde las 9:15 hasta las 10:00, a esas\u00a0 dos horas toco la hora de lengua y de matematicas, hicimos el examen de matematicas que trataba de las rectas y angulos y figuras planas y cuerpos geometricos. Cuando acabamos dimos el examen a Inma y lo grapamos, a la siguiente hora toco llingua y cultura, lo que hicimos fue pegar una lectura que trataba de las pinturas rupestres de diferentes cuevas, despues\u00a0 copiamos unas preguntas relacionadas con la lectura. Luego salimos al recreo, es la unica hora en la que nos dejan divertirnos. Por ultimo fuimos al polideportivo con Norma, hoy no fuimos dentro del polideportivo, fuimos a la parte de afuera donde habia dos balones de baloncesto y uno de futbol, despues de un largo tiempo jugando a baloncesto nos dejaron tiempo libre para jugar a futbol. Cuando llegamos a clase nos pusimos en fila para ir a casa.<\/p>\n<p>Jes\u00fas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viernes, 11 de mayo de 2018 Hola Diario: Hoy cuando llegamos a la fila nos pusimos a jugar y cuando llego Hector subimos a clase. A primera hora tuvimos ingles pero Yolanda no estaba, Inma nos dio los examenes de ingles para hacerlos, tuvimos tiempo desde las 9:15 hasta las 10:00, a esas\u00a0 dos horas &hellip; <a href=\"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2018\/05\/16\/diario-de-nuestra-clase\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">DIARIO DE NUESTRA CLASE<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":51,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/688"}],"collection":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/comments?post=688"}],"version-history":[{"count":2,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/688\/revisions"}],"predecessor-version":[{"id":695,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/688\/revisions\/695"}],"wp:attachment":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/media?parent=688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/categories?post=688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/tags?post=688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}