
{"id":621,"date":"2018-05-01T17:57:26","date_gmt":"2018-05-01T17:57:26","guid":{"rendered":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/?p=621"},"modified":"2018-05-01T17:57:26","modified_gmt":"2018-05-01T17:57:26","slug":"viaje-al-parlamento-y-monumentos-prerromanicos","status":"publish","type":"post","link":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2018\/05\/01\/viaje-al-parlamento-y-monumentos-prerromanicos\/","title":{"rendered":"VIAJE AL PARLAMENTO Y MONUMENTOS PRERROMANICOS"},"content":{"rendered":"<p>Hoy dia 24 de abril nos vamos en autobus a visitar El Parlamento de Oviedo, cuando llegamos entramos a El Parlamento, nada mas entrar se veia una puerta muy moderna y cosas muy lujosas del color del oro. Al entrar nos dieron una charla sobre la Organizacion Politica de Espa\u00f1a, despues subimos a la segunda planta y vimos a gente trabajar, all\u00ed habia muchos cuadros y habia uno que era del rey Felipe VI de Espa\u00f1a, luego entramos a otra sala que tenia unos asientos de color azul y otros de color rojo, la sala era peque\u00f1a. Por ultimo bajamos a la sala de abajo y nos encontramos muchos asientos que entre todos formaba un circulo, esa sala era para las votaciones de los partidos, enfrente de los microfonos de la mesa habia unos botones, el bot\u00f3n verde rectangular era para apagar y encender el microfono, el boton uno era para empezar la votacion y el cinco para terminarla. Despues nos fuimos a un monumento llamado Santa Maria De Naranco. Por dentro era de arenisca y nuestra guia nos dice que no toquemos los dibujos de arenisca porque si no se pierden y desaparecen, despues bajamos a la parte de abajo donde habia una puerta en la que todos miramos, parecia una sauna. Por ultimo visitamos San Miguel de Lillo, por fuera era muy llamativo, entramos y tenia dibujos alrededor de la puerta que todos significaban algo, tenia segundo piso pero estaba prohibido el paso. Despues nos fuimos de vuelta en autobus a el colegio.<\/p>\n<p>Jes\u00fas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy dia 24 de abril nos vamos en autobus a visitar El Parlamento de Oviedo, cuando llegamos entramos a El Parlamento, nada mas entrar se veia una puerta muy moderna y cosas muy lujosas del color del oro. Al entrar nos dieron una charla sobre la Organizacion Politica de Espa\u00f1a, despues subimos a la segunda &hellip; <a href=\"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2018\/05\/01\/viaje-al-parlamento-y-monumentos-prerromanicos\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">VIAJE AL PARLAMENTO Y MONUMENTOS PRERROMANICOS<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":51,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/621"}],"collection":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/comments?post=621"}],"version-history":[{"count":2,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/621\/revisions"}],"predecessor-version":[{"id":659,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/621\/revisions\/659"}],"wp:attachment":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/media?parent=621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/categories?post=621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/tags?post=621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}