
{"id":612,"date":"2018-05-01T18:04:21","date_gmt":"2018-05-01T18:04:21","guid":{"rendered":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/?p=612"},"modified":"2018-05-01T18:04:21","modified_gmt":"2018-05-01T18:04:21","slug":"visita-al-parlamento-asturiano-y-al-prerromanico-de-oviedo","status":"publish","type":"post","link":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2018\/05\/01\/visita-al-parlamento-asturiano-y-al-prerromanico-de-oviedo\/","title":{"rendered":"VISITA AL PARLAMENTO ASTURIANO Y AL PRERROM\u00c1NICO DE OVIEDO"},"content":{"rendered":"<p>El martes 24 de abril fuimos a Oviedo a visitar el Parlamento y dos edificios del prerrom\u00e1nico.<\/p>\n<p>Al llegar a Oviedo vimos desde el autob\u00fas, a la derecha, la iglesia de San Juli\u00e1n de los Prados. Cuando bajamos del autob\u00fas caminamos hasta el Parlamento.Una monitora nos explic\u00f3 que el edificio de la diputaci\u00f3n asturiana antes era un palacio y anterior un convento.<\/p>\n<p>Visitamos la sala Europa en la que el Presidente recibe a personalidades importantes y si se colocan sillas se hacen reuniones en las que cada partido pol\u00edtico debe acudir con al menos tres diputados y vimos la sala de la Constituci\u00f3n, donde hacen reuniones los diputados. Estaba todo decorado muy r\u00fastico, con fotos del Rey y otras personalidades y cuadros sobre cosas t\u00edpicas asturianas, mayar sidra, escudo de asturias, etc.<\/p>\n<p>Despu\u00e9s fuimos al Hemiciclo, en la planta baja y me sent\u00e9 en el esca\u00f1o de D. Emilio Jos\u00e9 Le\u00f3n Su\u00e1rez. Es el sal\u00f3n de plenos. Nos explicaron c\u00f3mo se usaban los botones durante el pleno, el verde para encender el micr\u00f3fono, el 1 para empezar la votaci\u00f3n, el 2 para votar NO, el 3 para abstenci\u00f3n, el 4 para S\u00cd y el 5 para acabar la votaci\u00f3n. Si alguien no llega a tiempo antes de que empiece la votaci\u00f3n no puede votar ni los de su equipo pueden hacerlo por otra persona.<\/p>\n<p>En caso de empate se vuelve a repetir la votaci\u00f3n hasta 3 veces. Si siempre se empata, dejan la idea archivada para decidir en otro momento.<\/p>\n<p>Antes de marcharnos nos regalaron una libreta, un boli y una bolsa.<\/p>\n<p>Depu\u00e9s comimos el apertivo en la plaza de la Catedral.<\/p>\n<p>Cuando terminamos salimos en autob\u00fas hacia Santa Mar\u00eda del Naranco, en Junio cumplir\u00e1 1170 a\u00f1os junto con San Miguel de Lillo que tambi\u00e9n visitamos.<\/p>\n<p>En Santa Mar\u00eda del Naranco hicimos la visita con otras personas, nos explicaron que se construy\u00f3 principalmente con los materiales de San Miguel de Lillo cuando se derrumb\u00f3. La mand\u00f3 construir Ramiro I como casa de verano.<\/p>\n<p>San Miguel de Lillo no es todo original por el derrumbamiento, conserva unas pinturas en piedra sobre v\u00edrgenes.<\/p>\n<p>\u00a1Me lo pas\u00e9 muy bien!<\/p>\n<p>Uday<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes 24 de abril fuimos a Oviedo a visitar el Parlamento y dos edificios del prerrom\u00e1nico. Al llegar a Oviedo vimos desde el autob\u00fas, a la derecha, la iglesia de San Juli\u00e1n de los Prados. Cuando bajamos del autob\u00fas caminamos hasta el Parlamento.Una monitora nos explic\u00f3 que el edificio de la diputaci\u00f3n asturiana antes &hellip; <a href=\"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2018\/05\/01\/visita-al-parlamento-asturiano-y-al-prerromanico-de-oviedo\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">VISITA AL PARLAMENTO ASTURIANO Y AL PRERROM\u00c1NICO DE OVIEDO<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":82,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"_links":{"self":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/612"}],"collection":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/comments?post=612"}],"version-history":[{"count":1,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/612\/revisions"}],"predecessor-version":[{"id":613,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/612\/revisions\/613"}],"wp:attachment":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/media?parent=612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/categories?post=612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/tags?post=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}