
{"id":197,"date":"2017-10-16T09:54:49","date_gmt":"2017-10-16T09:54:49","guid":{"rendered":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/?p=197"},"modified":"2017-10-16T09:54:49","modified_gmt":"2017-10-16T09:54:49","slug":"el-baobab-3","status":"publish","type":"post","link":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2017\/10\/16\/el-baobab-3\/","title":{"rendered":"EL BAOBAB."},"content":{"rendered":"<p>El \u00a0baobab \u00a0es \u00a0un \u00a0\u00e1rbol, es \u00a0grande \u00a0y con \u00a0un \u00a0tronco \u00a0ancho \u00a0y de \u00a0color \u00a0marr\u00f3n , sus \u00a0hojas \u00a0son \u00a0de \u00a0color \u00a0verde. Ese \u00e1rbol esta en Kalana \u00a0es un \u00a0pueblo \u00a0muy \u00a0peque\u00f1o. Los ni\u00f1os suelen ir \u00a0all\u00ed \u00a0a \u00a0aquel \u00e1rbol. A \u00a0m\u00ed \u00a0me \u00a0gustar\u00eda ir a el Baobab \u00a0y sacarme \u00a0una \u00a0foto \u00a0al lado \u00a0suyo \u00a0ser\u00eda \u00a0impresionante, solo que \u00a0Kalana esta \u00a0muy \u00a0lejos \u00a0de \u00a0aqu\u00ed de \u00a0d\u00f3nde \u00a0vivo \u00a0yo, por que \u00a0yo \u00a0vivo en Cand\u00e1s en un pueblo o villa es grande \u00a0se podr\u00eda decir.<\/p>\n<p>Un d\u00eda me dijeron que iva a ir a ver el baobab \u00a0a Kalana y yo \u00a0pensaba \u00a0que \u00a0era \u00a0mentira \u00a0pero \u00a0cuando \u00a0fui \u00a0dije: Esto es un sue\u00f1o \u00a0me pellizqu\u00e9 y \u00a0era \u00a0verdad, me \u00a0asust\u00e9\u00a0 mucho. Me \u00a0hice \u00a0una \u00a0foto \u00a0al \u00a0lado \u00a0del \u00a0Baobab \u00a0y \u00a0me hice \u00a0amigos y \u00a0amigas \u00a0una de \u00a0elllas \u00a0se llamaba Bintou \u00a0y \u00a0otro \u00a0Jes\u00fas. Jugamos al escondite \u00a0y \u00a0yo \u00a0me escond\u00ed \u00a0detr\u00e1s \u00a0del \u00a0Baobab con \u00a0Bintou por que contaba \u00a0Jes\u00fas. Fui a Kalana el \u00a024 de Mayo de 2017 \u00a0fu\u00ed \u00a0en \u00a0avi\u00f3n \u00a0y \u00a0volv\u00ed \u00a0en \u00a0avi\u00f3n \u00a0por que \u00a0entre \u00a0Cand\u00e1s \u00a0y \u00a0Kalana \u00a0hay \u00a0mar. Cu\u00e1ndo \u00a0llegu\u00e9 a \u00a0Cand\u00e1s \u00a0se \u00a0lo \u00a0dije \u00a0a \u00a0un \u00a0amigo \u00a0m\u00edo \u00a0se \u00a0llamaba \u00a0Iker. Me \u00a0lleve muchos \u00a0buenos \u00a0recuerdos \u00a0de \u00a0Kalana \u00a0del \u00a0Baobab \u00a0de \u00a0Bintou \u00a0y \u00a0tanbi\u00e9n \u00a0de \u00a0Jes\u00fas. \u00a1ME LO PASE SUPER BIEN! Solo \u00a0que \u00a0hac\u00eda \u00a0mucho \u00a0calor \u00a0por que \u00a0estaba \u00a0acostumbrado \u00a0al \u00a0fr\u00edo \u00a0de \u00a0Cand\u00e1s.<\/p>\n<h1><span style=\"color: #ff0000\">F<\/span><span style=\"color: #3366ff\">I<\/span><span style=\"color: #ff0000\">N<\/span><\/h1>\n<p>Alejandro Mart\u00ednez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u00a0baobab \u00a0es \u00a0un \u00a0\u00e1rbol, es \u00a0grande \u00a0y con \u00a0un \u00a0tronco \u00a0ancho \u00a0y de \u00a0color \u00a0marr\u00f3n , sus \u00a0hojas \u00a0son \u00a0de \u00a0color \u00a0verde. Ese \u00e1rbol esta en Kalana \u00a0es un \u00a0pueblo \u00a0muy \u00a0peque\u00f1o. Los ni\u00f1os suelen ir \u00a0all\u00ed \u00a0a \u00a0aquel \u00e1rbol. A \u00a0m\u00ed \u00a0me \u00a0gustar\u00eda ir a el Baobab \u00a0y sacarme \u00a0una \u00a0foto \u00a0al lado &hellip; <a href=\"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2017\/10\/16\/el-baobab-3\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">EL BAOBAB.<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":53,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/197"}],"collection":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/comments?post=197"}],"version-history":[{"count":3,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/197\/revisions"}],"predecessor-version":[{"id":214,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/197\/revisions\/214"}],"wp:attachment":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/media?parent=197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/categories?post=197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/tags?post=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}