
{"id":195,"date":"2017-10-16T09:48:05","date_gmt":"2017-10-16T09:48:05","guid":{"rendered":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/?p=195"},"modified":"2017-10-16T09:49:27","modified_gmt":"2017-10-16T09:49:27","slug":"cuento-baobab","status":"publish","type":"post","link":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2017\/10\/16\/cuento-baobab\/","title":{"rendered":"CUENTO BAOBAB"},"content":{"rendered":"<p>Erase una vez un cazador llamado Jose, este cazador era del Norte de Am\u00e9rica, \u00e9l fue de vacaciones a \u00c1frica, junto con sus dos hijos y su mujer. Jose iba a ir a cazar despu\u00e9s de la hora de comer, cuando lleg\u00f3 al lugar donde quer\u00eda cazar se dio cuenta de que no hab\u00eda llevado agua y estaba a muchos Kil\u00f3metros de su campamento, por suerte se acord\u00f3 de que algunos arboles de \u00c1frica llamados Baobab contienen agua, esos arboles pod\u00edan almacenar como 120.000 litros de agua, \u00a1Jose estaba salvado! pero no tenia herramientas para poder romper la corteza del \u00e1rbol y as\u00ed poder beber del agua que echaba. En ese momento a Jose se le ocurri\u00f3 una idea, era coger una rama e intentar romper la corteza y as\u00ed poder beber, pero las ramas del baobab no sirvieron para poder romper la corteza de ese \u00e1rbol, se le currio otra idea que era coger su navaja y romper la corteza, despu\u00e9s de varios intentos lo consigui\u00f3. Todo el agua que solt\u00f3 el \u00e1rbol le dio para poder llenar su garrafa y as\u00ed poder marchar a casa. Jose pensaba que ese \u00e1rbol era m\u00e1gico porque le hab\u00eda salvado la vida, cuando llego a casa le cont\u00f3 a sus hijos su gran aventura con el \u00e1rbol Baobab, de como le hab\u00eda salvado\u00a0 la vida conocer la historia de ese \u00e1rbol y lo \u00fatil que es conocer la naturaleza y sus secretos, los ni\u00f1os y su mujer se quedaron asombrados. Despu\u00e9s Jose se puso a escribir un cuento sobre su aventura y lo llamo: \u00abEl Baobab M\u00e1gico\u00bb. Ese cuento tenia tanta popularidad que todo el mundo lo compraba y Jose se hizo un famoso escritor.<\/p>\n<p>Jes\u00fas Cuadriello Rodriguez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erase una vez un cazador llamado Jose, este cazador era del Norte de Am\u00e9rica, \u00e9l fue de vacaciones a \u00c1frica, junto con sus dos hijos y su mujer. Jose iba a ir a cazar despu\u00e9s de la hora de comer, cuando lleg\u00f3 al lugar donde quer\u00eda cazar se dio cuenta de que no hab\u00eda llevado &hellip; <a href=\"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2017\/10\/16\/cuento-baobab\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">CUENTO BAOBAB<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":51,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/195"}],"collection":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/comments?post=195"}],"version-history":[{"count":3,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/195\/revisions"}],"predecessor-version":[{"id":210,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/195\/revisions\/210"}],"wp:attachment":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/media?parent=195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/categories?post=195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/tags?post=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}