
{"id":157,"date":"2017-10-14T15:27:24","date_gmt":"2017-10-14T15:27:24","guid":{"rendered":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/?p=157"},"modified":"2017-10-14T15:27:24","modified_gmt":"2017-10-14T15:27:24","slug":"el-baobab","status":"publish","type":"post","link":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2017\/10\/14\/el-baobab\/","title":{"rendered":"EL BAOBAB"},"content":{"rendered":"<p>En el a\u00f1o 2010, en el barrio La Matiella de Cand\u00e1s, hab\u00eda un baobab plantado en el prado a la orilla de la carretera. El \u00e1rbol ten\u00eda m\u00e1s de 1000 a\u00f1os.<\/p>\n<p>Las propiedades del \u00e1rbol era desconocidas por los habitantes de Cand\u00e1s.<\/p>\n<p>Unos ni\u00f1os llamados Amador, Rafa y Pablo siempre iban a jugar a la zona del baobab y contaban historias a la sombra de sus ramas.<\/p>\n<p>Una tarde, Amador lleg\u00f3 contando una triste noticia:<\/p>\n<p>-Cuando fui al supermercado escuch\u00e9 a unos obreros hablar sobre el baobab, dec\u00edan que lo iban a talar para despejar la zona, cont\u00f3 Amador al grupo.<\/p>\n<p>-\u00a1Tenemos que demostrar que no se puede talar!, exclam\u00f3 Pablo.<\/p>\n<p>&#8211; Ya que en Cand\u00e1s no se conoce la especie, podemos investigar sobre ella para saber sus propiedades buenas y perjudiciales, dijo Rafa.<\/p>\n<p>En sus casas, cada uno busc\u00f3 informaci\u00f3n y estudi\u00f3 el \u00e1rbol. Rafa estudi\u00f3 sus frutos y cont\u00f3 que de su pulpa se obten\u00eda un l\u00edquido blanco m\u00e1s nutritivo\u00a0 que la leche materna. Pablo estudi\u00f3 las hojas, que ten\u00edan Vitaminas A, C, E y\u00a0 F y eran beneficiosas para la piel. Amador estudi\u00f3 su savia,\u00a0 pero esa no ten\u00eda propiedades especiales.<\/p>\n<p>Entre los tres prepararon un escrito al Ayuntamiento para solicitar que no lo cortaran. El alcalde valor\u00f3 la petici\u00f3n y acept\u00f3 no cortar el \u00e1rbol.<\/p>\n<p>As\u00ed los ni\u00f1os pudieron seguir pasando las tardes de juego a la sombra del baobab.<\/p>\n<p>Uday.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el a\u00f1o 2010, en el barrio La Matiella de Cand\u00e1s, hab\u00eda un baobab plantado en el prado a la orilla de la carretera. El \u00e1rbol ten\u00eda m\u00e1s de 1000 a\u00f1os. Las propiedades del \u00e1rbol era desconocidas por los habitantes de Cand\u00e1s. Unos ni\u00f1os llamados Amador, Rafa y Pablo siempre iban a jugar a la &hellip; <a href=\"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2017\/10\/14\/el-baobab\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">EL BAOBAB<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":82,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/157"}],"collection":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":1,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/157\/revisions"}],"predecessor-version":[{"id":159,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/157\/revisions\/159"}],"wp:attachment":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/media?parent=157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/categories?post=157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/tags?post=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}