
{"id":149,"date":"2017-10-14T15:16:36","date_gmt":"2017-10-14T15:16:36","guid":{"rendered":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/?p=149"},"modified":"2017-10-14T15:16:36","modified_gmt":"2017-10-14T15:16:36","slug":"los-africanos","status":"publish","type":"post","link":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2017\/10\/14\/los-africanos\/","title":{"rendered":"LOS  AFRICANOS"},"content":{"rendered":"<p style=\"text-align: left\">Un d\u00eda, un ni\u00f1o nuevo que se llamaba Alain vino al cole por que se hab\u00eda mudado de \u00c1frica. Era un ni\u00f1o de 12 a\u00f1os, alto con pelo moreno y ojos marrones. Le gustaba el deporte, como por ejemplo:correr o jugar al baloncesto con sus amigos cerca de un \u00e1rbol que se llamaba baobab, en los alrededores de su pueblo.<\/p>\n<p style=\"text-align: left\">Nos cont\u00f3 que un d\u00eda mientra estaba jugando al escondite encontr\u00f3 una cueva secreta, cuando entr\u00f3 miro a su alrededor y encontr\u00f3 diamantes en las paredes y en el suelo. R\u00e1pidamente fue a avisar a su madre. Cuando esta lo vio se puso muy nerviosa, \u00a1eran ricos!. La madre, intento coger todos los diamantes\u00a0que pudo y volvi\u00f3\u00a0 a casa, rodeando la plaza central del pueblo, sin que nadie sospechara lo que en llevaba en sus bolsillos. Cuando llego a casa el padre de Alain, la madre le cont\u00f3 todo lo\u00a0sucedido y el padre r\u00e1pidamente pens\u00f3 un escondite para los diamantes, el interior del \u00abosito mimoso\u00bb de su hermana peque\u00f1a Juana, del cual no se separaba mas que el rato que iba al colegio.<\/p>\n<p style=\"text-align: left\">A la ma\u00f1ana siguiente, y sin llamar mucho la atenci\u00f3n,\u00a0 el padre de Alain cogi\u00f3 el coche, un diamante de un tama\u00f1o, mas bien peque\u00f1o\u00a0 y\u00a0 se fue todo lo r\u00e1pido que pudo al centro de al ciudad a tratar de venderlo para conseguir un poco de dinero mientras la madre y Alain iban de vuelta\u00a0la cueva a por mas diamantes.<\/p>\n<p style=\"text-align: left\">Con ese dinero que su padre consigui\u00f3 por la venta del diamante, Alain y su familia comenzaron a tener algunas comodidades que hasta entonces no hab\u00edan podido tener. Poco a poco su vida fue mejorando hasta que, sin despertar muchas sospechas entre sus vecinos, consiguieron juntar el dinero suficiente para poder viajar a Europa en busca de una vida mejor.<\/p>\n<h6 style=\"text-align: left\">LUCAS Y\u00c1\u00d1EZ COBI\u00c1N<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00eda, un ni\u00f1o nuevo que se llamaba Alain vino al cole por que se hab\u00eda mudado de \u00c1frica. Era un ni\u00f1o de 12 a\u00f1os, alto con pelo moreno y ojos marrones. Le gustaba el deporte, como por ejemplo:correr o jugar al baloncesto con sus amigos cerca de un \u00e1rbol que se llamaba baobab, en &hellip; <a href=\"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/2017\/10\/14\/los-africanos\/\" class=\"more-link\">Seguir leyendo <span class=\"screen-reader-text\">LOS  AFRICANOS<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":58,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/149"}],"collection":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/comments?post=149"}],"version-history":[{"count":4,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/149\/revisions"}],"predecessor-version":[{"id":176,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/posts\/149\/revisions\/176"}],"wp:attachment":[{"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/media?parent=149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/categories?post=149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aulastic.com\/blogs2\/cuaderno\/wp-json\/wp\/v2\/tags?post=149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}